{"id":3937,"date":"2022-07-22T08:00:00","date_gmt":"2022-07-22T11:00:00","guid":{"rendered":"https:\/\/coodesh.com\/blog\/?p=3937"},"modified":"2024-01-05T07:41:49","modified_gmt":"2024-01-05T10:41:49","slug":"estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb","status":"publish","type":"post","link":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/","title":{"rendered":"Estudo de caso: conhe\u00e7a a cultura organizacional no Airbnb"},"content":{"rendered":"\n<p>Experi\u00eancia e rela\u00e7\u00f5es humanas. Essas s\u00e3o as palavras-chave da cultura organizacional no Airbnb. A startup norte-americana, presente em 191 pa\u00edses, se baseia na experi\u00eancia do h\u00f3spede e do anfitri\u00e3o para oferecer a melhor solu\u00e7\u00e3o em servi\u00e7o de hospedagem. E tamb\u00e9m quer proporcionar uma boa experi\u00eancia ao funcion\u00e1rio, que pode escolher entre trabalhar no modelo presencial ou remoto, entre outros benef\u00edcios.&nbsp;<\/p>\n\n\n\n<p><strong>A startup nasceu em 2008 da necessidade de dois amigos de dividirem as despesas do apartamento em que moravam ap\u00f3s um reajuste de aluguel.<\/strong> Hoje ela conta com 5 mil funcion\u00e1rios em todo o mundo e \u00e9 considerada case de sucesso no RH.&nbsp;<\/p>\n\n\n\n<p>Mas como aplicar as boas pr\u00e1ticas da empresa, que est\u00e1 avaliada em mais de US$ 100 bilh\u00f5es, em pequenas e m\u00e9dias startups? Confira alguns insights neste conte\u00fado.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 o Airbnb?<\/h2>\n\n\n\n<p>Todos conhecem o <a href=\"https:\/\/www.airbnb.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Airbnb<\/a>, mas n\u00e3o custa nada relembrar um pouco da sua hist\u00f3ria e da sua presen\u00e7a atual no mercado.&nbsp;<\/p>\n\n\n\n<p><strong>Ele surgiu em 2008 dentro do contexto de economia colaborativa, que \u00e9 baseada no compartilhamento de bens e servi\u00e7os sem precisar adquiri-los.<\/strong> \u00c9 neste mesmo cen\u00e1rio que surgiu o Uber em 2009.&nbsp;<\/p>\n\n\n\n<p>Dois jovens de S\u00e3o Francisco, na Calif\u00f3rnia, Estados Unidos, precisavam dividir as despesas de um apartamento ap\u00f3s um reajuste do aluguel. Foi quando eles souberam que iria ocorrer um evento na cidade com gera\u00e7\u00e3o de demanda de hospedagem.&nbsp;<\/p>\n\n\n\n<p>Eles anunciaram \u201cAir Bed and Breakfast\u201d e, para surpresa, houve interessados. Assim, a ideia foi ganhando corpo e eles lan\u00e7aram o Airbnb, que hoje tem 150 milh\u00f5es de usu\u00e1rios.<\/p>\n\n\n\n<p>No in\u00edcio, todos pensaram que seria uma loucura algu\u00e9m aceitar abrir as portas da sua casa para desconhecidos. Entretanto, com a formata\u00e7\u00e3o do projeto foi poss\u00edvel conquistar simpatizantes, que usam o servi\u00e7o devido \u00e0 experi\u00eancia de se sentir em casa e n\u00e3o num quarto impessoal de hotel.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como \u00e9 o employer branding?<\/h2>\n\n\n\n<p>Com o tempo, a startup gerou muitos processos internos para atrair e reter uma equipe alinhada \u00e0 cultura organizacional no Airbnb.&nbsp;<\/p>\n\n\n\n<p><strong>Um deles \u00e9 o employer branding, que \u00e9 a marca empregadora, respons\u00e1vel tamb\u00e9m por gerar uma experi\u00eancia positiva no colaborador.&nbsp;<\/strong><\/p>\n\n\n\n<p>Por essa raz\u00e3o, entre os benef\u00edcios corporativos oferecidos est\u00e3o:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Universidade corporativa;<\/li><li>Bolsa-aux\u00edlio;<\/li><li>Bolsa de estudo;<\/li><li>Vale-alimenta\u00e7\u00e3o;<\/li><li>Vale-refei\u00e7\u00e3o;<\/li><li>Estacionamento;<\/li><li>Biciclet\u00e1rio;<\/li><li>Vale-transporte;<\/li><li>Assist\u00eancia m\u00e9dica e odontol\u00f3gica;<\/li><li>Seguro de vida;<\/li><li>Hor\u00e1rio flex\u00edvel.&nbsp;<\/li><\/ul>\n\n\n\n<p>Al\u00e9m disso, uma quest\u00e3o que est\u00e1 no centro das discuss\u00f5es do RH ultimamente \u00e9 o trabalho remoto. No Airbnb, os funcion\u00e1rios podem escolher qual modelo trabalhar. Veja mais a seguir.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Como o trabalho remoto \u00e9 tratado?<\/h2>\n\n\n\n<p>O CEO e fundador do Airbnb, Brian Chesky, mandou um e-mail para toda a equipe no in\u00edcio de 2022 informando que <strong>os funcion\u00e1rios poderiam trabalhar onde se sentissem mais produtivos.&nbsp;<\/strong><\/p>\n\n\n\n<p>Al\u00e9m disso, que o trabalho remoto seria adotado permanentemente mesmo ap\u00f3s o controle da pandemia da Covid-19.&nbsp;<\/p>\n\n\n\n<p>Antes da pandemia, a empresa adotava o modelo presencial. Por\u00e9m, seus escrit\u00f3rios tinham plantas mais modernas, parecendo-se com uma casa, ou ainda abertos, sem salas privativas. Assim, as pessoas podiam escolher em qual esta\u00e7\u00e3o trabalhar.&nbsp;<\/p>\n\n\n\n<p>Ali\u00e1s, o modelo j\u00e1 estava sendo adotado em outras empresas jovens do Vale do Sil\u00edcio, al\u00e9m de Google e Meta.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">5 recursos do trabalho remoto e flex\u00edvel&nbsp;<\/h2>\n\n\n\n<p>Chesky tamb\u00e9m anunciou no Twitter os 5 recursos principais da pol\u00edtica de flexibilidade da empresa no que diz respeito ao trabalho remoto. Veja quais s\u00e3o esses recursos e se eles fariam sentido para a sua empresa:&nbsp;<\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Voc\u00ea pode trabalhar em casa ou no escrit\u00f3rio;<\/li><li>Pode se mudar para qualquer lugar do pa\u00eds e sua remunera\u00e7\u00e3o n\u00e3o ser\u00e1 alterada (visto que em cidades menores, as empresas costumam pagar menos);<\/li><li>Voc\u00ea tem a flexibilidade de viver e trabalhar em 170 pa\u00edses por at\u00e9 90 dias por ano em cada local (incentivando ser n\u00f4made digital);<\/li><li>Haver\u00e1 encontros regulares para reuni\u00f5es de equipe, sendo que a maioria dos funcion\u00e1rios se conectar\u00e1 pessoalmente a cada trimestre por cerca de uma semana;<\/li><li>Haver\u00e1 um roteiro com dois lan\u00e7amentos de produtos principais por ano, fazendo a equipe trabalhar de forma coordenada (seja presencial, remoto ou h\u00edbrido).<\/li><\/ol>\n\n\n\n<h2 class=\"wp-block-heading\">Cultura baseada nas rela\u00e7\u00f5es humanas&nbsp;<\/h2>\n\n\n\n<p><strong>O ponto forte da cultura organizacional no Airbnb \u00e9 a cren\u00e7a na for\u00e7a das rela\u00e7\u00f5es humanas. <\/strong>Afinal, a empresa nasceu acreditando que as pessoas s\u00e3o boas. Assim, h\u00f3spede e anfitri\u00e3o n\u00e3o tentariam tirar proveito um do outro nem causariam preju\u00edzos financeiros.&nbsp;<\/p>\n\n\n\n<p>\u00c9 claro que j\u00e1 houve problemas e ainda haver\u00e3o, mas a empresa trabalha firme no prop\u00f3sito de que as rela\u00e7\u00f5es humanas podem ser boas.&nbsp;<\/p>\n\n\n\n<p>Al\u00e9m disso, o Airbnb acredita na for\u00e7a das comunidades. Dessa forma, a startup foca no compartilhamento de informa\u00e7\u00f5es e a redu\u00e7\u00e3o de barreiras entre as pessoas.&nbsp;<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Pertencimento&nbsp;<\/h3>\n\n\n\n<p>O <a href=\"https:\/\/coodesh.com\/blog\/rh-tech\/people-growth\/\" target=\"_blank\" rel=\"noreferrer noopener\">profissional alinhado<\/a> com essa cultura, tamb\u00e9m \u00e9 estimulado a se sentir integrado \u00e0 organiza\u00e7\u00e3o, que incentiva o pertencimento.<\/p>\n\n\n\n<p>Segundo os fundadores, por muito tempo se pensou que o Airbnb era uma startup de aluguel de casas. <strong>Mas, na verdade, todos estamos em casa. Por isso, essa no\u00e7\u00e3o de pertencer a qualquer lugar do mundo.&nbsp;<\/strong><\/p>\n\n\n\n<p>Com os funcion\u00e1rios tendo a liberdade de trabalhar em qualquer cidade que desejarem, tendo apenas um endere\u00e7o fixo para correspond\u00eancias e normas trabalhistas, o Airbnb incentiva a liberdade.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Ali\u00e1s, a marca passou recentemente por um processo de rebranding. Nesse contexto, ela lan\u00e7ou o slogan #belonganywhere. Com isso, os funcion\u00e1rios passaram a se sentir ainda mais parte da organiza\u00e7\u00e3o.&nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Import\u00e2ncia da cultura organizacional no Airbnb&nbsp;<\/h2>\n\n\n\n<p>O CEO e fundador do Airbnb, Brian Chesky, escreveu um e-mail \u00e0 equipe no ano de 2013 valorizando a cultura organizacional no Airbnb.&nbsp;<\/p>\n\n\n\n<p><strong>O texto, que <\/strong><a href=\"https:\/\/medium.com\/@bchesky\/dont-fuck-up-the-culture-597cde9ee9d4\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>pode ser conferido aqui<\/strong><\/a><strong>, afirma que tudo pode mudar, menos a cultura.<\/strong> Ali\u00e1s, ela est\u00e1 presente em cada detalhe, desde a forma de enviar um e-mail at\u00e9 uma decis\u00e3o importante para o mercado.&nbsp;<\/p>\n\n\n\n<p>De maneira geral, o CEO pediu que ningu\u00e9m estragasse a cultura da empresa, pois atrav\u00e9s dela nem \u00e9 preciso criar tantos processos internos, visto que as tarefas fluir\u00e3o de maneira mais natural.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>Nossa cultura \u00e9 a base da nossa empresa. Podemos n\u00e3o ser muito lembrados depois que nos formos, e se o Airbnb for daqui a 100 anos, certamente n\u00e3o seremos um site de reservas para casas. Estaremos muito al\u00e9m disso em nossa evolu\u00e7\u00e3o (sem mencionar que, daqui a 100 anos, as crian\u00e7as perguntar\u00e3o aos av\u00f3s quais eram os sites).<\/em><\/p><p><\/p><cite> <em>Brian Chesky<\/em>, fundador do Airbnb <\/cite><\/blockquote>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/calendly.com\/coodesh\/premium?utm_source=blog&amp;utm_medium=contratar-dev-jr&amp;month=2022-06\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"535\" src=\"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-1024x535.png\" alt=\"contrate desenvolvedores\" class=\"wp-image-2582\" srcset=\"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-1024x535.png 1024w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-300x157.png 300w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-768x401.png 768w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-561x293.png 561w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-1122x586.png 1122w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-364x190.png 364w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-728x380.png 728w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-608x318.png 608w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-758x396.png 758w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed-1152x602.png 1152w, https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/01\/Coodesh-Contrate-Desenvolvedores-Linkedin-Feed.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption><a href=\"https:\/\/calendly.com\/coodesh\/premium?utm_source=blog&amp;utm_medium=contratar-dev-jr&amp;month=2022-06\" target=\"_blank\" rel=\"noreferrer noopener\">Agende uma call de demonstra\u00e7\u00e3o com um dos nossos consultores  <\/a><\/figcaption><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Conclus\u00e3o&nbsp;<\/h2>\n\n\n\n<p>Embora ainda vejamos muitas empresas com culturas organizacionais baseadas em hierarquia e no modelo tradicional, \u00e9 importante encontrar inspira\u00e7\u00e3o em organiza\u00e7\u00f5es como o Airbnb, que cresceu alinhado com o contexto de compartilhamento de bens, apostando nas rela\u00e7\u00f5es humanas.&nbsp;<\/p>\n\n\n\n<p>Portanto, <strong>\u00e9 necess\u00e1rio que a empresa j\u00e1 nas\u00e7a definindo o seu prop\u00f3sito, com o seu respectivo papel na sociedade.<\/strong>&nbsp;<\/p>\n\n\n\n<p>Gostou do modelo de cultura organizacional do Airbnb? Saiba mais tamb\u00e9m sobre a <a href=\"https:\/\/coodesh.com\/blog\/candidates\/cultura-home-office-vantagens-e-desafios-para-desenvolvedores-e-equipes-tech\/\" target=\"_blank\" rel=\"noreferrer noopener\">cultura do home office<\/a> neste conte\u00fado do blog da Coodesh.&nbsp;<\/p>\n\n\n\n<p>A Coodesh \u00e9 uma startup de recrutamento tech e de code assessment para a testagem de desenvolvedores.&nbsp;<\/p>\n\n\n\n<p><a href=\"https:\/\/coodesh.com\/auth\/signup\/companies?origin=blog-b2b-article\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Cadastre-se<\/strong><\/a><strong> agora mesmo. Conhe\u00e7a os nossos recursos no plano gratuito e comece a avaliar, recrutar e testar desenvolvedores remotos para a sua empresa<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Experi\u00eancia e rela\u00e7\u00f5es humanas. Essas s\u00e3o as palavras-chave da cultura organizacional no Airbnb. A startup norte-americana, presente em 191 pa\u00edses, se baseia na experi\u00eancia do h\u00f3spede e do anfitri\u00e3o para oferecer a melhor solu\u00e7\u00e3o em servi\u00e7o de hospedagem. E tamb\u00e9m quer proporcionar uma boa experi\u00eancia ao funcion\u00e1rio, que pode escolher entre trabalhar no modelo presencial [&hellip;] <a class=\"g1-link g1-link-more\" href=\"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":4148,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[811,812,810,233,617,212,813,66,104,809],"class_list":{"0":"post-3937","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-rh-tech","8":"tag-airbnb","9":"tag-case","10":"tag-employee-experience","11":"tag-home-office","12":"tag-hospedagem","13":"tag-plataforma","14":"tag-proposito","15":"tag-rh","16":"tag-startup","17":"tag-valores"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cultura organizacional no Airbnb: saiba o que move a startup<\/title>\n<meta name=\"description\" content=\"A experi\u00eancia est\u00e1 em 1\u00ba lugar. Por isso, a cultura organizacional no Airbnb tamb\u00e9m est\u00e1 ligada \u00e0 experi\u00eancia de cada funcion\u00e1rio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cultura organizacional no Airbnb: saiba o que move a startup\" \/>\n<meta property=\"og:description\" content=\"A experi\u00eancia est\u00e1 em 1\u00ba lugar. Por isso, a cultura organizacional no Airbnb tamb\u00e9m est\u00e1 ligada \u00e0 experi\u00eancia de cada funcion\u00e1rio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog: Recrutar Desenvolvedores e Conte\u00fado de Programa\u00e7\u00e3o\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-22T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-05T10:41:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/06\/cultura-organizacional-no-airbnb-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Coodesh\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Coodesh\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/\"},\"author\":{\"name\":\"Coodesh\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#\\\/schema\\\/person\\\/be89698e2ad35891807e4ba9cd5bbb9e\"},\"headline\":\"Estudo de caso: conhe\u00e7a a cultura organizacional no Airbnb\",\"datePublished\":\"2022-07-22T11:00:00+00:00\",\"dateModified\":\"2024-01-05T10:41:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/\"},\"wordCount\":1302,\"publisher\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cultura-organizacional-no-airbnb-scaled.jpg\",\"keywords\":[\"Airbnb\",\"case\",\"employee experience\",\"home office\",\"hospedagem\",\"plataforma\",\"prop\u00f3sito\",\"RH\",\"startup\",\"valores\"],\"articleSection\":[\"RH Tech\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/\",\"url\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/\",\"name\":\"Cultura organizacional no Airbnb: saiba o que move a startup\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cultura-organizacional-no-airbnb-scaled.jpg\",\"datePublished\":\"2022-07-22T11:00:00+00:00\",\"dateModified\":\"2024-01-05T10:41:49+00:00\",\"description\":\"A experi\u00eancia est\u00e1 em 1\u00ba lugar. Por isso, a cultura organizacional no Airbnb tamb\u00e9m est\u00e1 ligada \u00e0 experi\u00eancia de cada funcion\u00e1rio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cultura-organizacional-no-airbnb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/cultura-organizacional-no-airbnb-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"cultura organizacional no airbnb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RH Tech\",\"item\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/rh-tech\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Estudo de caso: conhe\u00e7a a cultura organizacional no Airbnb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/\",\"name\":\"Blog: Recrutar Desenvolvedores e Conte\u00fado de Programa\u00e7\u00e3o\",\"description\":\"Conte\u00fados para ajudar sua empresa a contratar profissionais de tecnologia e dicas para programadores sobre: carreira, hard skills e soft skills. Confira! \",\"publisher\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#organization\",\"name\":\"Coodesh\",\"url\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Original2x.png\",\"contentUrl\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/08\\\/Original2x.png\",\"width\":800,\"height\":246,\"caption\":\"Coodesh\"},\"image\":{\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/#\\\/schema\\\/person\\\/be89698e2ad35891807e4ba9cd5bbb9e\",\"name\":\"Coodesh\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc57adf8637e672646668162ba8d75bb47498857be3d93593ecab8b644ba46c7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc57adf8637e672646668162ba8d75bb47498857be3d93593ecab8b644ba46c7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/cc57adf8637e672646668162ba8d75bb47498857be3d93593ecab8b644ba46c7?s=96&d=mm&r=g\",\"caption\":\"Coodesh\"},\"description\":\"Descubra habilidades. Elimine achismos. Decida com dados. Seja para construir uma equipe de sucesso ou aprimorar habilidades, as nossas solu\u00e7\u00f5es baseadas em ci\u00eancia e impulsionada por IA te levam aonde voc\u00ea precisa chegar!\",\"url\":\"https:\\\/\\\/coodesh.com\\\/blog\\\/author\\\/coodesh\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cultura organizacional no Airbnb: saiba o que move a startup","description":"A experi\u00eancia est\u00e1 em 1\u00ba lugar. Por isso, a cultura organizacional no Airbnb tamb\u00e9m est\u00e1 ligada \u00e0 experi\u00eancia de cada funcion\u00e1rio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/","og_locale":"pt_BR","og_type":"article","og_title":"Cultura organizacional no Airbnb: saiba o que move a startup","og_description":"A experi\u00eancia est\u00e1 em 1\u00ba lugar. Por isso, a cultura organizacional no Airbnb tamb\u00e9m est\u00e1 ligada \u00e0 experi\u00eancia de cada funcion\u00e1rio.","og_url":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/","og_site_name":"Blog: Recrutar Desenvolvedores e Conte\u00fado de Programa\u00e7\u00e3o","article_published_time":"2022-07-22T11:00:00+00:00","article_modified_time":"2024-01-05T10:41:49+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/06\/cultura-organizacional-no-airbnb-scaled.jpg","type":"image\/jpeg"}],"author":"Coodesh","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Coodesh","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#article","isPartOf":{"@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/"},"author":{"name":"Coodesh","@id":"https:\/\/coodesh.com\/blog\/#\/schema\/person\/be89698e2ad35891807e4ba9cd5bbb9e"},"headline":"Estudo de caso: conhe\u00e7a a cultura organizacional no Airbnb","datePublished":"2022-07-22T11:00:00+00:00","dateModified":"2024-01-05T10:41:49+00:00","mainEntityOfPage":{"@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/"},"wordCount":1302,"publisher":{"@id":"https:\/\/coodesh.com\/blog\/#organization"},"image":{"@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#primaryimage"},"thumbnailUrl":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/06\/cultura-organizacional-no-airbnb-scaled.jpg","keywords":["Airbnb","case","employee experience","home office","hospedagem","plataforma","prop\u00f3sito","RH","startup","valores"],"articleSection":["RH Tech"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/","url":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/","name":"Cultura organizacional no Airbnb: saiba o que move a startup","isPartOf":{"@id":"https:\/\/coodesh.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#primaryimage"},"image":{"@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#primaryimage"},"thumbnailUrl":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/06\/cultura-organizacional-no-airbnb-scaled.jpg","datePublished":"2022-07-22T11:00:00+00:00","dateModified":"2024-01-05T10:41:49+00:00","description":"A experi\u00eancia est\u00e1 em 1\u00ba lugar. Por isso, a cultura organizacional no Airbnb tamb\u00e9m est\u00e1 ligada \u00e0 experi\u00eancia de cada funcion\u00e1rio.","breadcrumb":{"@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#primaryimage","url":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/06\/cultura-organizacional-no-airbnb-scaled.jpg","contentUrl":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2022\/06\/cultura-organizacional-no-airbnb-scaled.jpg","width":2560,"height":1440,"caption":"cultura organizacional no airbnb"},{"@type":"BreadcrumbList","@id":"https:\/\/coodesh.com\/blog\/rh-tech\/estudo-de-caso-conheca-a-cultura-organizacional-no-airbnb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/coodesh.com\/blog\/"},{"@type":"ListItem","position":2,"name":"RH Tech","item":"https:\/\/coodesh.com\/blog\/rh-tech\/"},{"@type":"ListItem","position":3,"name":"Estudo de caso: conhe\u00e7a a cultura organizacional no Airbnb"}]},{"@type":"WebSite","@id":"https:\/\/coodesh.com\/blog\/#website","url":"https:\/\/coodesh.com\/blog\/","name":"Blog: Recrutar Desenvolvedores e Conte\u00fado de Programa\u00e7\u00e3o","description":"Conte\u00fados para ajudar sua empresa a contratar profissionais de tecnologia e dicas para programadores sobre: carreira, hard skills e soft skills. Confira! ","publisher":{"@id":"https:\/\/coodesh.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coodesh.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/coodesh.com\/blog\/#organization","name":"Coodesh","url":"https:\/\/coodesh.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/coodesh.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2020\/08\/Original2x.png","contentUrl":"https:\/\/coodesh.com\/blog\/wp-content\/uploads\/2020\/08\/Original2x.png","width":800,"height":246,"caption":"Coodesh"},"image":{"@id":"https:\/\/coodesh.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/coodesh.com\/blog\/#\/schema\/person\/be89698e2ad35891807e4ba9cd5bbb9e","name":"Coodesh","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/cc57adf8637e672646668162ba8d75bb47498857be3d93593ecab8b644ba46c7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/cc57adf8637e672646668162ba8d75bb47498857be3d93593ecab8b644ba46c7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cc57adf8637e672646668162ba8d75bb47498857be3d93593ecab8b644ba46c7?s=96&d=mm&r=g","caption":"Coodesh"},"description":"Descubra habilidades. Elimine achismos. Decida com dados. Seja para construir uma equipe de sucesso ou aprimorar habilidades, as nossas solu\u00e7\u00f5es baseadas em ci\u00eancia e impulsionada por IA te levam aonde voc\u00ea precisa chegar!","url":"https:\/\/coodesh.com\/blog\/author\/coodesh\/"}]}},"wps_subtitle":"","_links":{"self":[{"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/posts\/3937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/comments?post=3937"}],"version-history":[{"count":3,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/posts\/3937\/revisions"}],"predecessor-version":[{"id":3996,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/posts\/3937\/revisions\/3996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/media\/4148"}],"wp:attachment":[{"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/media?parent=3937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/categories?post=3937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coodesh.com\/blog\/wp-json\/wp\/v2\/tags?post=3937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}